{"id":3749,"date":"2018-06-24T11:02:58","date_gmt":"2018-06-24T09:02:58","guid":{"rendered":"https:\/\/www.electrosuisse.ch\/startseite\/"},"modified":"2026-05-11T08:36:30","modified_gmt":"2026-05-11T06:36:30","slug":"startseite","status":"publish","type":"page","link":"https:\/\/www.electrosuisse.ch\/fr\/","title":{"rendered":"Startseite"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<div class=\"tiles_container tiles_container--top\"><div class=\"tiles row\"><div class=\"tile tile--normal tile--one_third col-xs-12\"><div class=\"tile__inside\"><div class=\"tile__media\"><picture><source srcset=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2026\/04\/persoenliche-mitgliedschaft-electrosuisse-headerbild-585x500-1-585x500.jpg\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2026\/04\/persoenliche-mitgliedschaft-electrosuisse-headerbild-585x500-1-585x500.jpg\" alt=\"Adh\u00e9sion \u00abBasic\u00bb\" \/><\/picture><\/div><div class=\"tile__caption\"><h3>Adh\u00e9sion \u00abBasic\u00bb<\/h3><p>Votre acc\u00e8s au r\u00e9seau d'experts<br \/>\r\n\u00e0 partir de CHF 50 par an<\/p><div class=\"button button--arrow\"><div><div class=\"arrow\">Plus<\/div><\/div><\/div><\/div><a href=\"https:\/\/www.electrosuisse.ch\/fr\/devenez-membre\/adhesion-personnelle\/\" class=\"full\">En savoir plus sur Adh\u00e9sion \u00abBasic\u00bb<\/a><\/div><\/div><div class=\"tile tile--normal tile--two_third col-xs-12\"><div class=\"tile__inside\"><div class=\"tile__media\"><picture><source media=\"(min-width: 1281px)\" srcset=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2018\/12\/normung_electrosuisse_big.jpg\"><source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2018\/12\/normung_electrosuisse_big.jpg\"><source media=\"(min-width: 586px)\" srcset=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2018\/12\/normung_electrosuisse_big.jpg\"><source media=\"(max-width: 585px)\" srcset=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2018\/12\/normung_electrosuisse_big.jpg\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2018\/12\/normung_electrosuisse_big.jpg\" alt=\"Normalisation\" \/><\/picture><\/div><div class=\"tile__caption\"><h3>Normalisation<\/h3><p>Participer activement \u00e0 l\u2019\u00e9laboration des normes nationales et internationales.<\/p><div class=\"button button--arrow\"><div><div class=\"arrow\">Plus<\/div><\/div><\/div><\/div><a href=\"https:\/\/www.electrosuisse.ch\/fr\/normalisation\/pourquoi-normaliser\/\" class=\"full\">En savoir plus sur Normalisation<\/a><\/div><\/div><div class=\"tile tile--normal tile--two_third col-xs-12\"><div class=\"tile__inside\"><div class=\"tile__media\"><picture><source media=\"(min-width: 1281px)\" srcset=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2025\/11\/ES_Bild_Key_Visual_Bildungsangebot_1150_500.jpg\"><source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2025\/11\/ES_Bild_Key_Visual_Bildungsangebot_1150_500-585x500.jpg\"><source media=\"(min-width: 586px)\" srcset=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2025\/11\/ES_Bild_Key_Visual_Bildungsangebot_1150_500.jpg\"><source media=\"(max-width: 585px)\" srcset=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2025\/11\/ES_Bild_Key_Visual_Bildungsangebot_1150_500-585x500.jpg\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2025\/11\/ES_Bild_Key_Visual_Bildungsangebot_1150_500.jpg\" alt=\"Recueil de formation 2026\" \/><\/picture><\/div><div class=\"tile__caption\"><h3>Recueil de formation 2026<\/h3><p>Notre nouveau recueil de formation est disponible: d\u00e9couvrez notre offre vari\u00e9e de formation continue !<\/p><div class=\"button button--arrow\"><div><div class=\"arrow\">Plus<\/div><\/div><\/div><\/div><a href=\"https:\/\/www.electrosuisse.ch\/fr\/manifestation\/recueil-de-formations\/\" class=\"full\">En savoir plus sur Recueil de formation 2026<\/a><\/div><\/div><div class=\"tile tile--normal tile--one_third col-xs-12\"><div class=\"tile__inside\"><div class=\"tile__media\"><picture><source srcset=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2023\/04\/Carriere-samir-jareb-585x500-1-585x500.jpg\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2023\/04\/Carriere-samir-jareb-585x500-1-585x500.jpg\" alt=\"Travailler chez Electrosuisse\" \/><\/picture><\/div><div class=\"tile__caption\"><h3>Travailler chez Electrosuisse<\/h3><p>Nous offrons la vari\u00e9t\u00e9, un super esprit d\u2019\u00e9quipe et beaucoup de libert\u00e9.<\/p><div class=\"button button--arrow\"><div><div class=\"arrow\">Plus<\/div><\/div><\/div><\/div><a href=\"https:\/\/www.electrosuisse.ch\/fr\/carriere\/\" class=\"full\">En savoir plus sur Travailler chez Electrosuisse<\/a><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row el_class=&#8221;lead&#8221;][vc_column][vc_column_text css=&#8221;&#8221;]<\/p>\n<h1>Electrosuisse, l&#8217;organisation sp\u00e9cialis\u00e9e pour l&#8217;\u00e9lectrotechnique, les technologies de l&#8217;\u00e9nergie et de l&#8217;information<\/h1>\n<p>En tant qu\u2019organisation sp\u00e9cialis\u00e9e reconnue et ind\u00e9pendante, Electrosuisse propose des prestations et des produits de premier ordre dans les domaines de <a href=\"https:\/\/www.electrosuisse.ch\/fr\/inspektion-engineering\/wer-wir-sind\/\">l\u2019inspection, du conseil, du contr\u00f4le<\/a>, de la <a href=\"https:\/\/www.electrosuisse.ch\/fr\/normung\/warum-normung\/\">normalisation<\/a> et de la formation continue. Electrosuisse s&#8217;engage en outre pour le transfert de connaissances et les \u00e9changes entre sp\u00e9cialistes en organisant des \u00e9v\u00e9nements \u00e0 l\u2019intention des professionnels de la branche ainsi que des <a href=\"https:\/\/www.electrosuisse.ch\/fr\/tous-les-vnements\/\">conf\u00e9rences sp\u00e9cialis\u00e9es<\/a>. Toutes ces activit\u00e9s ont pour objectif de promouvoir une application de l&#8217;\u00e9lectrotechnique qui soit s\u00fbre, \u00e9conomique et respectueuse de l\u2019environnement.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2>Nos prochains \u00e9v\u00e9nements<\/h2>\n<p>[\/vc_column_text]<div class=\"wpb_carousel_column wpb_carousel_column--event wpb_content_element\"><div class=\"wpb_wrapper\"><div class=\"event_container\"><div class=\"owl-carousel owl-theme\"><div class=\"event\"><a href=\"https:\/\/www.electrosuisse.ch\/fr\/manifestations\/journee-dinformation-pour-electriciens-dexploitation\/\" class=\"full\">Journ\u00e9e d'information pour \u00e9lectriciens d'exploitation<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2026\/01\/vorschaubild.jpg\" alt=\"Journ\u00e9e d'information pour \u00e9lectriciens d'exploitation\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Journ\u00e9e d'information pour \u00e9lectriciens d'exploitation<\/h3><p class=\"event_date\">d\u00e8s le 18 mai 2026<\/p><p class=\"event_place\">Gen\u00e8ve, Lausanne<\/p><\/div><div class=\"button button--arrow-text\"><span>aller \u00e0 l\u2019\u00e9v\u00e9nement<\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.electrosuisse.ch\/fr\/tagung\/informationstagung-fuer-betriebselektriker\/\" class=\"full\">Informationstagung f\u00fcr Betriebselektriker<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2025\/11\/KeyVisual_BE-Tagung-2026_Opacc-585x400.jpg\" alt=\"Informationstagung f\u00fcr Betriebselektriker\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Informationstagung f\u00fcr Betriebselektriker<\/h3><p class=\"event_date\">21 mai 2026<\/p><p class=\"event_place\">Online<\/p><\/div><div class=\"button button--arrow-text\"><span>aller \u00e0 l\u2019\u00e9v\u00e9nement<\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.electrosuisse.ch\/fr\/tagung\/netzelektrikertag\/\" class=\"full\">Netzelektrikertag 2026<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2025\/06\/netzelektriker_2_585x345.png\" alt=\"Netzelektrikertag 2026\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Netzelektrikertag 2026<\/h3><p class=\"event_date\">2 juin 2026<\/p><p class=\"event_place\">Altes Spital - Solothurn<\/p><\/div><div class=\"button button--arrow-text\"><span>aller \u00e0 l\u2019\u00e9v\u00e9nement<\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.electrosuisse.ch\/fr\/tagung\/webinar-serie-on-air-blitzschutz-und-erdung\/\" class=\"full\">Webinar Serie 'on Air'<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2021\/12\/On_air_585x345.jpg\" alt=\"Webinar Serie 'on Air'\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Webinar Serie 'on Air'<\/h3><p class=\"event_topic\">Blitzschutz und Erdung (NIV) \u2013 Ausf\u00fchrung und Pr\u00fcfung<\/p><p class=\"event_date\">8 juin 2026<\/p><p class=\"event_place\">Online<\/p><\/div><div class=\"button button--arrow-text\"><span>aller \u00e0 l\u2019\u00e9v\u00e9nement<\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.forumfred.ch\/\" target=\"_blank\" class=\"full\">Forum FRED<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2023\/06\/KV_FRED_585x345.jpg\" alt=\"Forum FRED\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Forum FRED<\/h3><p class=\"event_date\">9 juin 2026<\/p><p class=\"event_place\">Lausanne - Beaulieu<\/p><\/div><div class=\"button button--arrow-text\"><span>Site Web de l\u2019\u00e9v\u00e9nement <\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.forumfred.ch\/\" target=\"_blank\" class=\"full\">Forum FRED<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2023\/06\/KV_FRED_585x345.jpg\" alt=\"Forum FRED\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Forum FRED<\/h3><p class=\"event_date\">9 juin 2026<\/p><p class=\"event_place\">Beaulieu, Lausanne<\/p><\/div><div class=\"button button--arrow-text\"><span>Site Web de l\u2019\u00e9v\u00e9nement <\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.electrosuisse.ch\/fr\/tagung\/fachtagung-fuer-sicherheitsbeauftragte-sibe\/\" class=\"full\">Fachtagung f\u00fcr Sicherheitsbeauftragte 2026<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2025\/02\/Fachtagung-fuer-Sicherheitsbeauftragte-585x345-1.png\" alt=\"Fachtagung f\u00fcr Sicherheitsbeauftragte 2026\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Fachtagung f\u00fcr Sicherheitsbeauftragte 2026<\/h3><p class=\"event_date\">11 juin 2026<\/p><p class=\"event_place\">Sursee, Oberkirch - Campus<\/p><\/div><div class=\"button button--arrow-text\"><span>aller \u00e0 l\u2019\u00e9v\u00e9nement<\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.electrosuisse.ch\/fr\/manifestations\/powertage\/\" class=\"full\">Electrosuisse aux Powertagen 2026<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2024\/02\/Powertage_keyvisual_585-585x300.png\" alt=\"Electrosuisse aux Powertagen 2026\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Electrosuisse aux Powertagen 2026<\/h3><p class=\"event_date\">17 juin 2026<\/p><p class=\"event_place\">Zurich Oerlikon<\/p><\/div><div class=\"button button--arrow-text\"><span>aller \u00e0 l\u2019\u00e9v\u00e9nement<\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.electrosuisse.ch\/fr\/tagung\/electrosuisse-impuls-webinar-nachweis-fuer-schaltgeraetekombinationen\/\" class=\"full\">Webinar Serie 'Electrosuisse Impuls'<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2026\/02\/Electrosuisse-Impuls-vorschaubilder-585x500.jpg\" alt=\"Webinar Serie 'Electrosuisse Impuls'\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Webinar Serie 'Electrosuisse Impuls'<\/h3><p class=\"event_topic\">Nachweis f\u00fcr Schaltger\u00e4tekombinationen<\/p><p class=\"event_date\">23 juin 2026<\/p><p class=\"event_place\">Online<\/p><\/div><div class=\"button button--arrow-text\"><span>aller \u00e0 l\u2019\u00e9v\u00e9nement<\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.electrosuisse.ch\/fr\/tagung\/elektroplanertag\/\" class=\"full\">Elektroplanertag 2026<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2026\/02\/elektroplanertag-2026-vorschaubild-electrosuisse-585x500.jpg\" alt=\"Elektroplanertag 2026\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Elektroplanertag 2026<\/h3><p class=\"event_date\">25 juin 2026<\/p><p class=\"event_place\">Baden - Trafo<\/p><\/div><div class=\"button button--arrow-text\"><span>aller \u00e0 l\u2019\u00e9v\u00e9nement<\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.electrosuisse.ch\/fr\/tagung\/instandhaltungstagung\/\" class=\"full\">Instandhaltungstagung<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2026\/03\/Instandhaltungstagung_2026_Key_vorschaubild.jpg\" alt=\"Instandhaltungstagung\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Instandhaltungstagung<\/h3><p class=\"event_date\">d\u00e8s le 25 ao\u00fbt 2026<\/p><p class=\"event_place\">Bern - Kreuz, Chur - Brandis 12, Pratteln - Courtyard by Marriott Basel, Regensdorf - M\u00f6venpick, Wil - Stadtsaal<\/p><\/div><div class=\"button button--arrow-text\"><span>aller \u00e0 l\u2019\u00e9v\u00e9nement<\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.electrosuisse.ch\/fr\/tagung\/electrosuisse-impuls-sng-491000\/\" class=\"full\">Webinar Serie 'Electrosuisse Impuls'<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2026\/02\/Electrosuisse-Impuls-vorschaubilder-585x500.jpg\" alt=\"Webinar Serie 'Electrosuisse Impuls'\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Webinar Serie 'Electrosuisse Impuls'<\/h3><p class=\"event_topic\">SNG 491000<\/p><p class=\"event_date\">1<sup>er<\/sup> septembre 2026<\/p><p class=\"event_place\">Online<\/p><\/div><div class=\"button button--arrow-text\"><span>aller \u00e0 l\u2019\u00e9v\u00e9nement<\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.electrosuisse.ch\/fr\/tagung\/webinar-serie-on-air-innerer-blitzschutz\/\" class=\"full\">Webinar Serie 'on Air'<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2021\/12\/On_air_585x345.jpg\" alt=\"Webinar Serie 'on Air'\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Webinar Serie 'on Air'<\/h3><p class=\"event_topic\">Innerer Blitzschutz \u2013 aus der Praxis<\/p><p class=\"event_date\">8 septembre 2026<\/p><p class=\"event_place\">Online<\/p><\/div><div class=\"button button--arrow-text\"><span>aller \u00e0 l\u2019\u00e9v\u00e9nement<\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.electrosuisse.ch\/fr\/tagung\/schaltanlagen-praktikertag\/\" class=\"full\">Schaltanlagen-Praktikertag<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2025\/09\/schaltanlagen-praktikertag-2-585x345-1.png\" alt=\"Schaltanlagen-Praktikertag\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Schaltanlagen-Praktikertag<\/h3><p class=\"event_date\">16 septembre 2026<\/p><p class=\"event_place\">Aarau \u2013 Kultur- und Kongresshaus<\/p><\/div><div class=\"button button--arrow-text\"><span>aller \u00e0 l\u2019\u00e9v\u00e9nement<\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/anlagentagung.ch\/\" target=\"_blank\" class=\"full\">Anlagentagung<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2022\/11\/Key_Visual_Anlagentagung_585x345.jpg\" alt=\"Anlagentagung\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Anlagentagung<\/h3><p class=\"event_date\">17 septembre 2026<\/p><p class=\"event_place\">Aarau \u2013 Kultur- und Kongresshaus<\/p><\/div><div class=\"button button--arrow-text\"><span>Site Web de l\u2019\u00e9v\u00e9nement <\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/emobile-verkehrsforum.ch\/\" target=\"_blank\" class=\"full\">e-mobile Verkehrsforum<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2023\/04\/electrosuisse-e-mobile-verkehrsforum_preview.jpg\" alt=\"e-mobile Verkehrsforum\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>e-mobile Verkehrsforum<\/h3><p class=\"event_date\">24 septembre 2026<\/p><p class=\"event_place\">Z\u00fcrich - Technopark<\/p><\/div><div class=\"button button--arrow-text\"><span>Site Web de l\u2019\u00e9v\u00e9nement <\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.electrosuisse.ch\/fr\/tagung\/stromertage\/\" class=\"full\">StromerTAGE 2026<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2026\/03\/stormerTage-2026-electrosuisse-585x400.jpg\" alt=\"StromerTAGE 2026\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>StromerTAGE 2026<\/h3><p class=\"event_date\">d\u00e8s le 7 octobre 2026<\/p><p class=\"event_place\">Bern, Chur , M\u00fcnchenstein, St. Gallen, Z\u00fcrich <\/p><\/div><div class=\"button button--arrow-text\"><span>aller \u00e0 l\u2019\u00e9v\u00e9nement<\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.electrosuisse.ch\/fr\/tagung\/praktische-normenarbeit\/\" class=\"full\">CES Workshop: Praktische Normenarbeit<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2024\/04\/Banner_Landingpage_CES_Workshop_585x345.jpg\" alt=\"CES Workshop: Praktische Normenarbeit\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>CES Workshop: Praktische Normenarbeit<\/h3><p class=\"event_date\">13 octobre 2026<\/p><p class=\"event_place\">Olten - CZO Coachingzentrum Olten<\/p><\/div><div class=\"button button--arrow-text\"><span>aller \u00e0 l\u2019\u00e9v\u00e9nement<\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.electrosuisse.ch\/fr\/tagung\/forum-fuer-elektrofachleute\/\" class=\"full\">Forum f\u00fcr Elektrofachleute<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2025\/05\/Forum_fuer_Elektrofachleute_2025_585x345.png\" alt=\"Forum f\u00fcr Elektrofachleute\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Forum f\u00fcr Elektrofachleute<\/h3><p class=\"event_date\">d\u00e8s le 5 novembre 2026<\/p><p class=\"event_place\">Bern - Kursaal, Landquart - Forum , Luzern - Verkehrshaus, Regensdorf - M\u00f6venpick, Rorschach - W\u00fcrth Haus<\/p><\/div><div class=\"button button--arrow-text\"><span>aller \u00e0 l\u2019\u00e9v\u00e9nement<\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"http:\/\/www.gebaeudetechnik-kongress.ch\/\" target=\"_blank\" class=\"full\">Geb\u00e4udetechnik-Kongress meets Schweizer Geb\u00e4udetechnik und Planertag <\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2021\/08\/GTK_2021_585x345-1.jpg\" alt=\"Geb\u00e4udetechnik-Kongress meets Schweizer Geb\u00e4udetechnik und Planertag \" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Geb\u00e4udetechnik-Kongress meets Schweizer Geb\u00e4udetechnik und Planertag <\/h3><p class=\"event_date\">10 novembre 2026<\/p><p class=\"event_place\">Trafo Baden<\/p><\/div><div class=\"button button--arrow-text\"><span>Site Web de l\u2019\u00e9v\u00e9nement <\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/leitungsbau-tagung.ch\/\" target=\"_blank\" class=\"full\">Leitungsbau<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2023\/06\/Leitungsbau_585x345.jpg\" alt=\"Leitungsbau\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Leitungsbau<\/h3><p class=\"event_date\">11 novembre 2026<\/p><p class=\"event_place\">Aarau \u2013 Kultur- und Kongresshaus<\/p><\/div><div class=\"button button--arrow-text\"><span>Site Web de l\u2019\u00e9v\u00e9nement <\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.energiezukunft-forum.ch\/\" target=\"_blank\" class=\"full\">Energiezukunft meets Energy Startup Day<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2025\/07\/energiezukunft_2025_585x345.png\" alt=\"Energiezukunft meets Energy Startup Day\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Energiezukunft meets Energy Startup Day<\/h3><p class=\"event_date\">19 novembre 2026<\/p><p class=\"event_place\">Aarau \u2013 Kultur- und Kongresshaus<\/p><\/div><div class=\"button button--arrow-text\"><span>Site Web de l\u2019\u00e9v\u00e9nement <\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/forum-romand-energie.ch\/\" target=\"_blank\" class=\"full\">Forum Romand de l\u2019\u00c9nergie (Tagesveranstaltung)<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2024\/02\/Key-visual-romandenergie_585x345.png\" alt=\"Forum Romand de l\u2019\u00c9nergie (Tagesveranstaltung)\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Forum Romand de l\u2019\u00c9nergie (Tagesveranstaltung)<\/h3><p class=\"event_date\">26 novembre 2026<\/p><p class=\"event_place\">Ecublens - Swiss Tech Convention Center<\/p><\/div><div class=\"button button--arrow-text\"><span>Site Web de l\u2019\u00e9v\u00e9nement <\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/smartenergyparty.ch\/ecublens\/\" target=\"_blank\" class=\"full\">Smart Energy Party Romandie (Abendveranstaltung)<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2024\/03\/Smart_Energy_Party_Romandi_585x345.png\" alt=\"Smart Energy Party Romandie (Abendveranstaltung)\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Smart Energy Party Romandie (Abendveranstaltung)<\/h3><p class=\"event_date\">26 novembre 2026<\/p><p class=\"event_place\">Ecublens - Swiss Tech Convention Center<\/p><\/div><div class=\"button button--arrow-text\"><span>Site Web de l\u2019\u00e9v\u00e9nement <\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/forum-romand-energie.ch\/\" target=\"_blank\" class=\"full\">Forum Romand de l\u2019\u00c9nergie (manifestation en journ\u00e9e)<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2024\/02\/Key-visual-romandenergie_585x345.png\" alt=\"Forum Romand de l\u2019\u00c9nergie (manifestation en journ\u00e9e)\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Forum Romand de l\u2019\u00c9nergie (manifestation en journ\u00e9e)<\/h3><p class=\"event_date\">26 novembre 2026<\/p><p class=\"event_place\">Ecublens - Swiss Tech Convention Center<\/p><\/div><div class=\"button button--arrow-text\"><span>Site Web de l\u2019\u00e9v\u00e9nement <\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/smartenergyparty.ch\/ecublens\/\" target=\"_blank\" class=\"full\">Smart Energy Party Romandie (manifestation en soir\u00e9e)<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2024\/03\/Smart_Energy_Party_Romandi_585x345.png\" alt=\"Smart Energy Party Romandie (manifestation en soir\u00e9e)\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Smart Energy Party Romandie (manifestation en soir\u00e9e)<\/h3><p class=\"event_date\">26 novembre 2026<\/p><p class=\"event_place\">Ecublens - Swiss Tech Convention Center<\/p><\/div><div class=\"button button--arrow-text\"><span>Site Web de l\u2019\u00e9v\u00e9nement <\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.electrosuisse.ch\/fr\/tagung\/electrosuisse-impuls-arbeitssicherheit\/\" class=\"full\">Webinar Serie 'Electrosuisse Impuls'<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2026\/02\/Electrosuisse-Impuls-vorschaubilder-585x500.jpg\" alt=\"Webinar Serie 'Electrosuisse Impuls'\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Webinar Serie 'Electrosuisse Impuls'<\/h3><p class=\"event_topic\">Arbeitssicherheit <\/p><p class=\"event_date\">1<sup>er<\/sup> d\u00e9cembre 2026<\/p><p class=\"event_place\">Online<\/p><\/div><div class=\"button button--arrow-text\"><span>aller \u00e0 l\u2019\u00e9v\u00e9nement<\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.swiss-lighting-forum.ch\/\" target=\"_blank\" class=\"full\">Swiss Lighting Forum<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2020\/01\/SLF2020_585x500-1-585x500.jpg\" alt=\"Swiss Lighting Forum\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>Swiss Lighting Forum<\/h3><p class=\"event_date\">27 janvier 2027<\/p><p class=\"event_place\">Z\u00fcrich - Technopark<\/p><\/div><div class=\"button button--arrow-text\"><span>Site Web de l\u2019\u00e9v\u00e9nement <\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.ladeforum.ch\/\" target=\"_blank\" class=\"full\">e-mobile Lade Forum<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2022\/09\/Bild-Ladepark-frei-585x500-2-585x500.jpg\" alt=\"e-mobile Lade Forum\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>e-mobile Lade Forum<\/h3><p class=\"event_date\">9 mars 2027<\/p><p class=\"event_place\">Z\u00fcrich - Technopark<\/p><\/div><div class=\"button button--arrow-text\"><span>Site Web de l\u2019\u00e9v\u00e9nement <\/span><\/div><\/div><\/div><div class=\"event\"><a href=\"https:\/\/www.netzimpuls.ch\/\" target=\"_blank\" class=\"full\">NetzImpuls<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2023\/09\/NL_Banner_NetzImpuls_585x345.jpg\" alt=\"NetzImpuls\" \/><\/div><\/div><div class=\"event__content\"><div class=\"content\"><h3>NetzImpuls<\/h3><p class=\"event_date\">17 mars 2027<\/p><p class=\"event_place\">Aarau \u2013 Kultur- und Kongresshaus<\/p><\/div><div class=\"button button--arrow-text\"><span>Site Web de l\u2019\u00e9v\u00e9nement <\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;&#8221;]<\/p>\n<h2>Articles recommand\u00e9s<\/h2>\n<p>[\/vc_column_text]<div class=\"wpb_news_column wpb_content_element\"><div class=\"wpb_wrapper\"><div class=\"news_container\"><div class=\"owl-carousel owl-theme\"><div class=\"news\"><a href=\"https:\/\/www.bulletin.ch\/fr\/approches-innovantes-pour-des-calculs-de-securite-du-reseau-coordonnes\" class=\"full\"  target=\"_blank\">Approches innovantes pour des calculs de s\u00e9curit\u00e9 du r\u00e9seau coordonn\u00e9s<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2026\/05\/reseau-coordonnes_bulletin_electrosuisse-585x500.jpg\" alt=\"Approches innovantes pour des calculs de s\u00e9curit\u00e9 du r\u00e9seau coordonn\u00e9s\" \/><\/div><\/div><div class=\"news__content\"><div class=\"content\"><span class=\"date is-news-date\">12 mai 2026<\/span><h3>Approches innovantes pour des calculs de s\u00e9curit\u00e9 du r\u00e9seau coordonn\u00e9s<\/h3><p>La d\u00e9centralisation de la production et l\u2019int\u00e9gration des \u00e9nergies renouvelables intermittentes m\u00e8nent \u00e0 des changements de direction des flux de charge, n\u00e9cessitant de plus en plus de contre-mesures pour garantir la stabilit\u00e9 du r\u00e9seau. Or, les mesures prises par le gestionnaire du r\u00e9seau de transport peuvent entra\u00eener un transfert des flux de charge vers le r\u00e9seau de distribution et y provoquer des congestions, ou inversement. C'est l\u00e0 qu'intervient Opteso, un m\u00e9canisme de coordination qui garantit que les mesures propos\u00e9es par les syst\u00e8mes d\u2019aide \u00e0 la d\u00e9cision du GRT sont coordonn\u00e9es avec les GRD connect\u00e9s, via leurs propres syst\u00e8mes d\u2019aide \u00e0 la d\u00e9cision.<\/p><\/div><div class=\"button button--arrow-text\"><span>Lire l\u2019article<\/span><\/div><\/div><\/div><div class=\"news\"><a href=\"https:\/\/www.bulletin.ch\/fr\/le-passeport-batterie-vers-une-transparence-et-une-securite-accrues\" class=\"full\"  target=\"_blank\">Le passeport batterie: vers une transparence et une s\u00e9curit\u00e9 accrues<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2026\/05\/passport-batterie-bulletin-electrosuisse-585x500.jpg\" alt=\"Le passeport batterie: vers une transparence et une s\u00e9curit\u00e9 accrues\" \/><\/div><\/div><div class=\"news__content\"><div class=\"content\"><span class=\"date is-news-date\">5 mai 2026<\/span><h3>Le passeport batterie: vers une transparence et une s\u00e9curit\u00e9 accrues<\/h3><p>Jusqu\u2019\u00e0 pr\u00e9sent, les batteries des voitures \u00e9lectriques \u00e9taient une bo\u00eete noire. Cela a suscit\u00e9 des inqui\u00e9tudes, notamment quant \u00e0 la difficult\u00e9 de revendre les voitures \u00e9lectriques d\u2019occasion, car la dur\u00e9e de vie r\u00e9siduelle de la batterie n\u2019\u00e9tait pas claire. Le passeport batterie de l\u2019UE vise \u00e0 garantir la transparence dans ce domaine. Dans cet entretien, Nora Bartolom\u00e9 Guti\u00e9rrez, experte en gestion durable des d\u00e9chets d\u2019\u00e9quipements \u00e9lectriques et \u00e9lectroniques, donne un aper\u00e7u de la situation actuelle.<\/p><\/div><div class=\"button button--arrow-text\"><span>Lire l\u2019article<\/span><\/div><\/div><\/div><div class=\"news\"><a href=\"https:\/\/www.bulletin.ch\/fr\/remplacement-des-camions-diesel-par-des-vehicules-electriques\" class=\"full\"  target=\"_blank\">Remplacement des camions diesel par des v\u00e9hicules \u00e9lectriques<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2026\/04\/remplacement-des-camions-diesel-par-des-vehicules-electriques-bulletin-electrosuisse-585x500.jpg\" alt=\"Remplacement des camions diesel par des v\u00e9hicules \u00e9lectriques\" \/><\/div><\/div><div class=\"news__content\"><div class=\"content\"><span class=\"date is-news-date\">27 avril 2026<\/span><h3>Remplacement des camions diesel par des v\u00e9hicules \u00e9lectriques<\/h3><p>En 2025, un peu plus d\u2019un v\u00e9hicule utilitaire sur cinq d\u2019un poids total sup\u00e9rieur \u00e0 3,5 t \u00e9tait un v\u00e9hicule \u00e9lectrique \u00e0 batterie. Le chemin \u00e0 parcourir avant de parvenir \u00e0 une d\u00e9carbonation compl\u00e8te du transport routier de marchandises est donc encore long. Trois \u00e9tudes soutenues par l\u2019Office f\u00e9d\u00e9ral de l\u2019\u00e9nergie ont examin\u00e9 comment cet objectif pourrait \u00eatre atteint au cours des prochaines d\u00e9cennies.<\/p><\/div><div class=\"button button--arrow-text\"><span>Lire l\u2019article<\/span><\/div><\/div><\/div><div class=\"news\"><a href=\"https:\/\/www.bulletin.ch\/fr\/securisation-des-systemes-de-transport-intelligents-cooperatifs-en-suisse\" class=\"full\"  target=\"_blank\">S\u00e9curisation des syst\u00e8mes de transport intelligents coop\u00e9ratifs en Suisse<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2026\/04\/securisation-des-systemes-de-transport-intelligentes-cooperatifs-en-Suisse-bulletin-electrosuisse-585x500.jpg\" alt=\"S\u00e9curisation des syst\u00e8mes de transport intelligents coop\u00e9ratifs en Suisse\" \/><\/div><\/div><div class=\"news__content\"><div class=\"content\"><span class=\"date is-news-date\">11 avril 2026<\/span><h3>S\u00e9curisation des syst\u00e8mes de transport intelligents coop\u00e9ratifs en Suisse<\/h3><p>Les syst\u00e8mes de transport intelligents coop\u00e9ratifs (C-ITS) permettent l\u2019\u00e9change d\u2019informations en temps r\u00e9el entre v\u00e9hicules, infrastructures et usagers, promettant ainsi une circulation plus s\u00fbre, efficace et durable. Cette interconnexion croissante s\u2019accompagne toutefois de nouveaux risques, notamment en mati\u00e8re de cybers\u00e9curit\u00e9. Un projet de recherche lanc\u00e9 par l'OFROU a permis de d\u00e9finir une feuille de route pour la mise en place d\u2019un centre national des op\u00e9rations de s\u00e9curit\u00e9 d\u00e9di\u00e9 aux C-ITS. <\/p><\/div><div class=\"button button--arrow-text\"><span>Lire l\u2019article<\/span><\/div><\/div><\/div><div class=\"news\"><a href=\"https:\/\/www.bulletin.ch\/fr\/immissions-de-champs-magnetiques-dans-les-voitures-electriques\" class=\"full\"  target=\"_blank\">Immissions de champs magn\u00e9tiques dans les voitures \u00e9lectriques<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2026\/03\/Immissions-de-champs-magnetiques-dans-les-voitures-electriques-bulletin-electrosuisse-585x500.jpg\" alt=\"Immissions de champs magn\u00e9tiques dans les voitures \u00e9lectriques\" \/><\/div><\/div><div class=\"news__content\"><div class=\"content\"><span class=\"date is-news-date\">30 mars 2026<\/span><h3>Immissions de champs magn\u00e9tiques dans les voitures \u00e9lectriques<\/h3><p>Avec des puissances maximales de propulsion de plusieurs centaines de kilowatts, des valeurs de courant nettement sup\u00e9rieures \u00e0 500 A peuvent \u00eatre atteintes dans le groupe motopropulseur des voitures \u00e9lectriques. Des mesures syst\u00e9matiques ont \u00e9t\u00e9 effectu\u00e9es dans des conditions d\u2019exploitation r\u00e9alistes afin de d\u00e9terminer si les valeurs limites des immissions de champs magn\u00e9tiques \u00e0 l\u2019int\u00e9rieur du corps recommand\u00e9es par l\u2019ICNIRP \u00e9taient respect\u00e9es.<\/p><\/div><div class=\"button button--arrow-text\"><span>Lire l\u2019article<\/span><\/div><\/div><\/div><div class=\"news\"><a href=\"https:\/\/www.bulletin.ch\/fr\/les-centres-de-donnees-en-tant-que-gestionnaires-de-reseau\" class=\"full\"  target=\"_blank\">Les centres de donn\u00e9es en tant que gestionnaires de r\u00e9seau<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2026\/03\/bulletin-gestionnaires-resesau-585x500.jpg\" alt=\"Les centres de donn\u00e9es en tant que gestionnaires de r\u00e9seau\" \/><\/div><\/div><div class=\"news__content\"><div class=\"content\"><span class=\"date is-news-date\">23 mars 2026<\/span><h3>Les centres de donn\u00e9es en tant que gestionnaires de r\u00e9seau<\/h3><p>L\u2019essor de l\u2019informatique, et en particulier de l\u2019intelligence artificielle (IA), s\u2019accompagne en Suisse d\u2019une augmentation du nombre d\u2019entreprises exploitant des centres de donn\u00e9es dont les besoins \u00e9nerg\u00e9tiques \u00e9lev\u00e9s n\u00e9cessitent l\u2019installation de stations transformatrices. Cependant, les obligations li\u00e9es \u00e0 cette exploitation sont encore peu connues, ce qui peut entra\u00eener des risques pour la s\u00e9curit\u00e9 de ces installations.<\/p><\/div><div class=\"button button--arrow-text\"><span>Lire l\u2019article<\/span><\/div><\/div><\/div><div class=\"news\"><a href=\"https:\/\/bulletin.ch\/fr\" class=\"full\"  target=\"_blank\">Acc\u00e9l\u00e9rer la transition \u00e9nerg\u00e9tique gr\u00e2ce \u00e0 la supraconductivit\u00e9<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2026\/03\/bulletin-superaconductivite-585x500.jpg\" alt=\"Acc\u00e9l\u00e9rer la transition \u00e9nerg\u00e9tique gr\u00e2ce \u00e0 la supraconductivit\u00e9\" \/><\/div><\/div><div class=\"news__content\"><div class=\"content\"><span class=\"date is-news-date\">19 mars 2026<\/span><h3>Acc\u00e9l\u00e9rer la transition \u00e9nerg\u00e9tique gr\u00e2ce \u00e0 la supraconductivit\u00e9<\/h3><p>L\u2019\u00e9lectrification croissante ainsi que l\u2019essor fulgurant des infrastructures num\u00e9riques mettent le r\u00e9seau \u00e9lectrique sous pression. Celui doit \u00eatre renforc\u00e9 \u00e0 certains endroits, ce qui peut parfois \u00eatre difficile \u00e0 r\u00e9aliser avec des syst\u00e8mes de c\u00e2blage conventionnels. Dans de tels cas, avoir recours \u00e0 des c\u00e2bles supra\u00adconducteurs \u00e0 haute temp\u00e9rature (HTS) pr\u00e9sente plusieurs avantages. <\/p><\/div><div class=\"button button--arrow-text\"><span>Lire l\u2019article<\/span><\/div><\/div><\/div><div class=\"news\"><a href=\"https:\/\/www.bulletin.ch\/fr\/penser-les-infrastructures-de-maniere-integree\" class=\"full\"  target=\"_blank\">Penser les infrastructures de mani\u00e8re int\u00e9gr\u00e9e<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2026\/03\/bulletin-infrastructures-de-maniere-integree-585x500.jpg\" alt=\"Penser les infrastructures de mani\u00e8re int\u00e9gr\u00e9e\" \/><\/div><\/div><div class=\"news__content\"><div class=\"content\"><span class=\"date is-news-date\">2 mars 2026<\/span><h3>Penser les infrastructures de mani\u00e8re int\u00e9gr\u00e9e<\/h3><p>Le Gothard est bien plus qu\u2019un simple goulet g\u00e9ographique de la Suisse. Depuis des si\u00e8cles, il relie le nord et le sud, les peuples et les march\u00e9s, les cultures et les innovations. Aujourd\u2019hui, il se trouve \u00e0 nouveau au c\u0153ur d\u2019une transformation: il devient un symbole de la transition \u00e9nerg\u00e9tique et de la modernisation du r\u00e9seau \u00e9lectrique suisse. La nouvelle ligne c\u00e2bl\u00e9e dans le tunnel routier du Gothard montre comment cet axe strat\u00e9gique joue un r\u00f4le cl\u00e9 pour l\u2019avenir de notre pays, m\u00eame au XXIe si\u00e8cle.<\/p><\/div><div class=\"button button--arrow-text\"><span>Lire l\u2019article<\/span><\/div><\/div><\/div><div class=\"news\"><a href=\"https:\/\/www.bulletin.ch\/fr\/combien-de-cable-souterrain-le-reseau-de-transport-peut-il-supporter\" class=\"full\"  target=\"_blank\">Combien de c\u00e2ble souterrain le r\u00e9seau de transport peut-il supporter?<\/a><div class=\"news__img\"><div class=\"picture_container\"><img decoding=\"async\" src=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2026\/02\/bulletin_Erdkabel-585x500.jpg\" alt=\"Combien de c\u00e2ble souterrain le r\u00e9seau de transport peut-il supporter?\" \/><\/div><\/div><div class=\"news__content\"><div class=\"content\"><span class=\"date is-news-date\">16 f\u00e9vrier 2026<\/span><h3>Combien de c\u00e2ble souterrain le r\u00e9seau de transport peut-il supporter?<\/h3><p>Le r\u00e9seau de transport suisse assure non seulement une grande stabilit\u00e9 du r\u00e9seau en Suisse, mais rend \u00e9galement d\u2019importants services \u00e0 l\u2019\u00e9chelle inter\u00adnationale, gr\u00e2ce \u00e0 sa connexion au r\u00e9seau europ\u00e9en. Cependant, une grande partie de l\u2019infrastructure d\u00e9velopp\u00e9e au fil du temps est vieillissante et devra \u00eatre renouvel\u00e9e dans les ann\u00e9es \u00e0 venir. <\/p><\/div><div class=\"button button--arrow-text\"><span>Lire l\u2019article<\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row][vc_row el_class=&#8221;lead&#8221;][vc_column][vc_column_text css=&#8221;&#8221;] Electrosuisse, l&#8217;organisation sp\u00e9cialis\u00e9e pour l&#8217;\u00e9lectrotechnique, les technologies de l&#8217;\u00e9nergie et de l&#8217;information En tant qu\u2019organisation sp\u00e9cialis\u00e9e reconnue et ind\u00e9pendante, Electrosuisse propose des prestations et des produits de premier ordre dans les domaines de l\u2019inspection, du conseil, du contr\u00f4le, de la normalisation et de la formation continue. Electrosuisse s&#8217;engage en outre pour le [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":347,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-3749","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.4 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Organisation sp\u00e9cialis\u00e9e pour l\u2019\u00e9lectrotechnique et les technologies de l\u2019\u00e9nergie - Electrosuisse<\/title>\n<meta name=\"description\" content=\"En tant qu&#039;organisation sp\u00e9cialis\u00e9e reconnue et ind\u00e9pendante, Electrosuisse propose des services et des produits dans les domaines du conseil, du contr\u00f4le, de l&#039;ing\u00e9nierie, des essais, de la normalisation et de la formation continue. En organisant des \u00e9v\u00e9nements professionnels \u00e9tablis et des conf\u00e9rences sp\u00e9cialis\u00e9es, Electrosuisse favorise le transfert de connaissances et les \u00e9changes techniques. La promotion d&#039;une utilisation de l\u2019\u00e9lectricit\u00e9 s\u00fbre, \u00e9conomique et respectueuse de l&#039;environnement se trouve au c\u0153ur de toutes ses activit\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.electrosuisse.ch\/fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Organisation sp\u00e9cialis\u00e9e pour l\u2019\u00e9lectrotechnique et les technologies de l\u2019\u00e9nergie - Electrosuisse\" \/>\n<meta property=\"og:description\" content=\"En tant qu&#039;organisation sp\u00e9cialis\u00e9e reconnue et ind\u00e9pendante, Electrosuisse propose des services et des produits dans les domaines du conseil, du contr\u00f4le, de l&#039;ing\u00e9nierie, des essais, de la normalisation et de la formation continue. En organisant des \u00e9v\u00e9nements professionnels \u00e9tablis et des conf\u00e9rences sp\u00e9cialis\u00e9es, Electrosuisse favorise le transfert de connaissances et les \u00e9changes techniques. La promotion d&#039;une utilisation de l\u2019\u00e9lectricit\u00e9 s\u00fbre, \u00e9conomique et respectueuse de l&#039;environnement se trouve au c\u0153ur de toutes ses activit\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.electrosuisse.ch\/fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Electrosuisse\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T06:36:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2022\/12\/Electrosuisse_Ueber_uns_1578x650.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1578\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.electrosuisse.ch\/fr\/\",\"url\":\"https:\/\/www.electrosuisse.ch\/fr\/\",\"name\":\"Organisation sp\u00e9cialis\u00e9e pour l\u2019\u00e9lectrotechnique et les technologies de l\u2019\u00e9nergie - Electrosuisse\",\"isPartOf\":{\"@id\":\"https:\/\/www.electrosuisse.ch\/fr\/#website\"},\"datePublished\":\"2018-06-24T09:02:58+00:00\",\"dateModified\":\"2026-05-11T06:36:30+00:00\",\"description\":\"En tant qu'organisation sp\u00e9cialis\u00e9e reconnue et ind\u00e9pendante, Electrosuisse propose des services et des produits dans les domaines du conseil, du contr\u00f4le, de l'ing\u00e9nierie, des essais, de la normalisation et de la formation continue. En organisant des \u00e9v\u00e9nements professionnels \u00e9tablis et des conf\u00e9rences sp\u00e9cialis\u00e9es, Electrosuisse favorise le transfert de connaissances et les \u00e9changes techniques. La promotion d'une utilisation de l\u2019\u00e9lectricit\u00e9 s\u00fbre, \u00e9conomique et respectueuse de l'environnement se trouve au c\u0153ur de toutes ses activit\u00e9s.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.electrosuisse.ch\/fr\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.electrosuisse.ch\/fr\/#website\",\"url\":\"https:\/\/www.electrosuisse.ch\/fr\/\",\"name\":\"Electrosuisse\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.electrosuisse.ch\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.electrosuisse.ch\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.electrosuisse.ch\/fr\/#organization\",\"name\":\"Electrosuisse\",\"url\":\"https:\/\/www.electrosuisse.ch\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"contentUrl\":\"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png\",\"width\":696,\"height\":696,\"caption\":\"Electrosuisse\"},\"image\":{\"@id\":\"https:\/\/www.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all\",\"https:\/\/www.instagram.com\/electrosuisse1889\/\",\"https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw\"],\"description\":\"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Organisation sp\u00e9cialis\u00e9e pour l\u2019\u00e9lectrotechnique et les technologies de l\u2019\u00e9nergie - Electrosuisse","description":"En tant qu'organisation sp\u00e9cialis\u00e9e reconnue et ind\u00e9pendante, Electrosuisse propose des services et des produits dans les domaines du conseil, du contr\u00f4le, de l'ing\u00e9nierie, des essais, de la normalisation et de la formation continue. En organisant des \u00e9v\u00e9nements professionnels \u00e9tablis et des conf\u00e9rences sp\u00e9cialis\u00e9es, Electrosuisse favorise le transfert de connaissances et les \u00e9changes techniques. La promotion d'une utilisation de l\u2019\u00e9lectricit\u00e9 s\u00fbre, \u00e9conomique et respectueuse de l'environnement se trouve au c\u0153ur de toutes ses activit\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.electrosuisse.ch\/fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Organisation sp\u00e9cialis\u00e9e pour l\u2019\u00e9lectrotechnique et les technologies de l\u2019\u00e9nergie - Electrosuisse","og_description":"En tant qu'organisation sp\u00e9cialis\u00e9e reconnue et ind\u00e9pendante, Electrosuisse propose des services et des produits dans les domaines du conseil, du contr\u00f4le, de l'ing\u00e9nierie, des essais, de la normalisation et de la formation continue. En organisant des \u00e9v\u00e9nements professionnels \u00e9tablis et des conf\u00e9rences sp\u00e9cialis\u00e9es, Electrosuisse favorise le transfert de connaissances et les \u00e9changes techniques. La promotion d'une utilisation de l\u2019\u00e9lectricit\u00e9 s\u00fbre, \u00e9conomique et respectueuse de l'environnement se trouve au c\u0153ur de toutes ses activit\u00e9s.","og_url":"https:\/\/www.electrosuisse.ch\/fr\/","og_site_name":"Electrosuisse","article_modified_time":"2026-05-11T06:36:30+00:00","og_image":[{"width":1578,"height":650,"url":"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2022\/12\/Electrosuisse_Ueber_uns_1578x650.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.electrosuisse.ch\/fr\/","url":"https:\/\/www.electrosuisse.ch\/fr\/","name":"Organisation sp\u00e9cialis\u00e9e pour l\u2019\u00e9lectrotechnique et les technologies de l\u2019\u00e9nergie - Electrosuisse","isPartOf":{"@id":"https:\/\/www.electrosuisse.ch\/fr\/#website"},"datePublished":"2018-06-24T09:02:58+00:00","dateModified":"2026-05-11T06:36:30+00:00","description":"En tant qu'organisation sp\u00e9cialis\u00e9e reconnue et ind\u00e9pendante, Electrosuisse propose des services et des produits dans les domaines du conseil, du contr\u00f4le, de l'ing\u00e9nierie, des essais, de la normalisation et de la formation continue. En organisant des \u00e9v\u00e9nements professionnels \u00e9tablis et des conf\u00e9rences sp\u00e9cialis\u00e9es, Electrosuisse favorise le transfert de connaissances et les \u00e9changes techniques. La promotion d'une utilisation de l\u2019\u00e9lectricit\u00e9 s\u00fbre, \u00e9conomique et respectueuse de l'environnement se trouve au c\u0153ur de toutes ses activit\u00e9s.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.electrosuisse.ch\/fr\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.electrosuisse.ch\/fr\/#website","url":"https:\/\/www.electrosuisse.ch\/fr\/","name":"Electrosuisse","description":"","publisher":{"@id":"https:\/\/www.electrosuisse.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.electrosuisse.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.electrosuisse.ch\/fr\/#organization","name":"Electrosuisse","url":"https:\/\/www.electrosuisse.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","contentUrl":"https:\/\/www.electrosuisse.ch\/wp-content\/uploads\/2025\/04\/Electrosuisse_Logo_696x696.png","width":696,"height":696,"caption":"Electrosuisse"},"image":{"@id":"https:\/\/www.electrosuisse.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/electrosuisse-ag\/posts\/?feedView=all","https:\/\/www.instagram.com\/electrosuisse1889\/","https:\/\/www.youtube.com\/channel\/UCoOxohMiVE0Gjcdis1L09zw"],"description":"Electrosuisse ist eine anerkannte und unabh\u00e4ngige Fachorganisation, die erstklassige Dienstleistungen und Produkte in den Bereichen Inspektion, Beratung, Pr\u00fcfung, Zertifizierung, Normung und Weiterbildung anbietet. Unsere Expertise umfasst Elektrotechnik, Elektromobilit\u00e4t, Energieberatung, Geb\u00e4udeautomation und Photovoltaik in der Schweiz. Durch die Veranstaltung etablierter Branchen-Events und Fachtagungen f\u00f6rdert Electrosuisse den Wissenstransfer und den fachlichen Austausch. Im Mittelpunkt unserer T\u00e4tigkeiten steht die F\u00f6rderung der sicheren, wirtschaftlichen und umweltgerechten Anwendung der Elektrotechnik."}]}},"amp_enabled":false,"_links":{"self":[{"href":"https:\/\/www.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/pages\/3749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/comments?post=3749"}],"version-history":[{"count":16,"href":"https:\/\/www.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/pages\/3749\/revisions"}],"predecessor-version":[{"id":45148,"href":"https:\/\/www.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/pages\/3749\/revisions\/45148"}],"wp:attachment":[{"href":"https:\/\/www.electrosuisse.ch\/fr\/wp-json\/wp\/v2\/media?parent=3749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}